﻿{"id":1490,"date":"2013-03-21T17:24:12","date_gmt":"2013-03-21T23:24:12","guid":{"rendered":"https:\/\/www.uv.mx\/noticias\/?p=1490"},"modified":"2013-03-21T17:34:09","modified_gmt":"2013-03-21T23:34:09","slug":"mexico-requiere-un-verdadero-sistema-de-educacion-superior-aseguro-raul-arias-lovillo","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/noticias\/2013\/03\/21\/mexico-requiere-un-verdadero-sistema-de-educacion-superior-aseguro-raul-arias-lovillo\/","title":{"rendered":"M\u00e9xico requiere un verdadero sistema de educaci\u00f3n superior asegur\u00f3 Ra\u00fal Arias Lovillo"},"content":{"rendered":"<p><i><\/i><b><\/b>\u00a0<\/p>\n<ul>\n<li><i>El Rector de la UV particip\u00f3 en el encuentro \u201c\u00bfHacia d\u00f3nde va la ciencia en M\u00e9xico?\u201d<\/i><\/li>\n<li><i>Propuso crear en la ANUIES una comisi\u00f3n para la planeaci\u00f3n de un verdadero sistema de educaci\u00f3n superior<\/i><\/li>\n<\/ul>\n<p>\u00a0<a href=\"https:\/\/www.uv.mx\/noticias\/files\/2013\/03\/210313-rector-propuestas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1493 aligncenter\" alt=\"210313-rector-propuestas\" src=\"https:\/\/www.uv.mx\/noticias\/files\/2013\/03\/210313-rector-propuestas.jpg\" width=\"442\" height=\"294\" \/><\/a><\/p>\n<p style=\"text-align: center\"><em>Ra\u00fal Arias Lovillo, rector de la Universidad Veracruzana.<\/em><\/p>\n<p><em><strong>Alma Espinosa<\/strong><\/em><\/p>\n<p>M\u00e9xico requiere de un verdadero sistema de educaci\u00f3n superior, en el que las instituciones de educaci\u00f3n superior (IES) desempe\u00f1en un papel estrat\u00e9gico para el desarrollo nacional, asegur\u00f3 el rector de la Universidad Veracruzana (UV), Ra\u00fal Arias Lovillo, al participar en el evento \u201c\u00bfHacia d\u00f3nde va la ciencia en M\u00e9xico?\u201d, cuya primera jornada se realiz\u00f3 este jueves 21 de marzo en la USBI del <i>campus <\/i>Xalapa.<\/p>\n<p>\u201cHay que cambiar muchas cosas, entre ellas es necesario definir verdaderamente un sistema de educaci\u00f3n superior donde la docencia universitaria est\u00e9 \u00edntimamente vinculada a la investigaci\u00f3n, que haya un papel estrat\u00e9gico de la universidad p\u00fablica como palanca del desarrollo nacional\u201d, expres\u00f3.<\/p>\n<p>Durante su intervenci\u00f3n en la mesa \u201cLa investigaci\u00f3n en la educaci\u00f3n superior\u201d, el Rector destac\u00f3 que es preciso organizar un real sistema de educaci\u00f3n superior, pues el que existe no es un sistema como tal, sino un archipi\u00e9lago donde no hay una coordinaci\u00f3n en la toma de decisiones.<\/p>\n<p>Coment\u00f3 que si se revisa la estructura porcentual por profesi\u00f3n de los egresados y se cuestiona qui\u00e9n decidi\u00f3 su estructura, \u201cla respuesta es nadie\u201d, es el resultante de las decisiones desarticuladas de las IES mexicanas.<\/p>\n<p>\u00a0Arias Lovillo plante\u00f3 que las autoridades educativas han respondido a la educaci\u00f3n superior con las siguientes acciones: \u201caumento de la cobertura, incremento en la calidad de la educaci\u00f3n, profesores <i>Promep<\/i>, mejora de infraestructura, equipamientos, evaluaci\u00f3n, PIFI, cuerpos colegiados, proyectos especiales. Si las universidades ya hicimos todo lo que ten\u00edamos que hacer, \u00bfahora qu\u00e9 hacemos?\u201d.<\/p>\n<p>Y agreg\u00f3: \u201cHemos conservado el mismo patr\u00f3n organizacional, la misma organizaci\u00f3n del conocimiento, los mismos contenidos acad\u00e9micos, la misma gesti\u00f3n del conocimiento, el mismo modelo pedag\u00f3gico; en pocas palabras, el mismo paradigma educativo\u201d. Ante esta situaci\u00f3n llam\u00f3 a cambiar el paradigma educativo.<\/p>\n<p>Propuso, como primer paso, crear en la Asociaci\u00f3n Nacional de Universidades e Instituciones de Educaci\u00f3n Superior (ANUIES) un cuerpo colegiado de seis rectores (mismo n\u00famero de regiones del organismo) que conformen una comisi\u00f3n de planeaci\u00f3n del sistema de educaci\u00f3n superior, apoyados por los t\u00e9cnicos de la propia ANUIES.<\/p>\n<p>Explic\u00f3 que la primera tarea que deben llevar a cabo es la planeaci\u00f3n de la oferta educativa nacional y, posteriormente, dise\u00f1ar cada una de las piezas de la reforma del paradigma educativo del pa\u00eds. En un sistema as\u00ed, agreg\u00f3, ser\u00eda necesaria la libre circulaci\u00f3n de estudiantes y profesores de todas las IES y terminar con la centralizaci\u00f3n en el DF.<\/p>\n<p>El Rector de la UV destac\u00f3 que un tema fundamental es definir qu\u00e9 es universidad, pues en la actualidad \u201ca cualquier cosa se le llama como tal y eso no puede ser\u201d, pues no todas las escuelas cumplen con las funciones sustantivas de docencia, investigaci\u00f3n, vinculaci\u00f3n, difusi\u00f3n y distribuci\u00f3n social del conocimiento.<\/p>\n<p>\u00a0Adem\u00e1s, se\u00f1al\u00f3 que esta reflexi\u00f3n debe estar enfocada a mejorar las condiciones de vida de los mexicanos. \u201cSi queremos ser un pa\u00eds competitivo debemos analizar c\u00f3mo otros pa\u00edses lo han logrado, c\u00f3mo mejoraron su nivel de competitividad en la econom\u00eda mundial; y al hacerlo, nos percatamos que han planteado una distinta gesti\u00f3n del conocimiento. Por ello, si no abandonamos los patrones tradicionales en los que nos hemos movido en las \u00faltimas d\u00e9cadas, M\u00e9xico no saldr\u00e1 del triste papel que ha tenido los \u00faltimos a\u00f1os\u201d.<\/p>\n<p>Aunque existe un ambiente desolador en cuanto a los egresados de las universidades, dijo, hay estudios que se\u00f1alan que M\u00e9xico tiene potencial de crecimiento. \u201cPodemos ser un pa\u00eds exitoso. Es la hora de tomar decisiones, es la hora de que la clase pol\u00edtica tenga una visi\u00f3n de Estado que permita construir las condiciones para que M\u00e9xico sea exitoso.<\/p>\n<p>\u00a0En la mesa \u201cLa investigaci\u00f3n en la educaci\u00f3n superior\u201d tambi\u00e9n estuvieron los acad\u00e9micos Emilio Ribes I\u00f1esta, Carlos Pall\u00e1n Figueroa, Adri\u00e1n Acosta Silva, Salvador Malo \u00c1lvarez y Roberto Rodr\u00edguez G\u00f3mez.<\/p>\n<p>El programa \u201c\u00bfHacia d\u00f3nde va la ciencia en M\u00e9xico?\u201d \u2013iniciativa del <i>Conacyt<\/i>, la Academia Mexicana de Ciencias y el Consejo Consultivo de Ciencias de la Presidencia de la Rep\u00fablica\u2013, continuar\u00e1 este viernes 22 de marzo a partir de las 9:00 horas. Cabe destacar que tambi\u00e9n se transmite por el sistema de videoconferencias a todos los <i>campus<\/i> de la UV.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 El Rector de la UV particip\u00f3 en el encuentro \u201c\u00bfHacia d\u00f3nde va la ciencia en M\u00e9xico?\u201d Propuso crear en la ANUIES una comisi\u00f3n para la planeaci\u00f3n de un verdadero sistema de educaci\u00f3n superior \u00a0 Ra\u00fal Arias Lovillo, rector de la Universidad Veracruzana. Alma Espinosa M\u00e9xico requiere de un verdadero sistema de educaci\u00f3n superior, en [&hellip;]<\/p>\n","protected":false},"author":1395,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ventana_nueva":"","tipo_url":"","url":"","extracto":"","imagen_halign":"","imagen_valign":"","bg_size":"","text_hide":"","media_url":"","tipo_media":"","video_url":"","video_pos":"","video_youtube":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1490","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/posts\/1490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/users\/1395"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/comments?post=1490"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/posts\/1490\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/media?parent=1490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/categories?post=1490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/noticias\/wp-json\/wp\/v2\/tags?post=1490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}