{"id":18,"date":"2013-12-09T13:02:14","date_gmt":"2013-12-09T19:02:14","guid":{"rendered":"http:\/\/www.uv.mx\/personal\/gvega\/?p=18"},"modified":"2013-12-09T13:05:49","modified_gmt":"2013-12-09T19:05:49","slug":"alimentos-de-origen-animal","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/personal\/gvega\/2013\/12\/09\/alimentos-de-origen-animal\/","title":{"rendered":"Alimentos de origen animal"},"content":{"rendered":"<p><a href=\"http:\/\/www.uv.mx\/personal\/gvega\/files\/2013\/12\/alimentos.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19\" alt=\"alimentos\" src=\"http:\/\/www.uv.mx\/personal\/gvega\/files\/2013\/12\/alimentos.jpeg\" width=\"107\" height=\"81\" \/><\/a>Hola, esta es una peque\u00f1a imagen de los alimentos que inspeccionamos. Aqui faltaria leche, importante alimento rico en prote\u00ednas para el crecimiento de los ni\u00f1os. Adem\u00e1s detectaremos su adulteraci\u00f3n, que es una pr\u00e1ctica muy com\u00fan y fraudulenta de alterar los alimentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hola, esta es una peque\u00f1a imagen de los alimentos que inspeccionamos. Aqui faltaria leche, importante alimento rico en prote\u00ednas para el crecimiento de los ni\u00f1os. Adem\u00e1s detectaremos su adulteraci\u00f3n, que es una pr\u00e1ctica muy com\u00fan y fraudulenta de alterar los alimentos.<\/p>\n","protected":false},"author":1041,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-18","post","type-post","status-publish","format-standard","hentry","category-miblog"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/posts\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/users\/1041"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/posts\/18\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/media?parent=18"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/categories?post=18"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/personal\/gvega\/wp-json\/wp\/v2\/tags?post=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}