{"id":152754,"date":"2025-03-13T19:47:40","date_gmt":"2025-03-14T01:47:40","guid":{"rendered":"https:\/\/www.uv.mx\/prensa\/?p=152754"},"modified":"2025-03-13T19:47:40","modified_gmt":"2025-03-14T01:47:40","slug":"universidad-veracruzana-rehabilito-cancha-de-futbol-bardas","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/prensa\/general\/universidad-veracruzana-rehabilito-cancha-de-futbol-bardas\/","title":{"rendered":"Universidad Veracruzana rehabilit\u00f3 cancha de futbol bardas"},"content":{"rendered":"<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><i><span data-contrast=\"auto\">En la Unidad Deportiva del Campus para la\u202fCultura, las Artes y el Deporte\u202f(Campus CAD)<\/span><\/i><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><span data-ccp-props=\"{&quot;335559685&quot;:720}\">\u00a0<\/span><\/p>\n<ul>\n<li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><i><span data-contrast=\"auto\">El Rector mencion\u00f3 que su administraci\u00f3n trabaja a fin de que la comunidad estudiantil cuente con las condiciones adecuadas para desarrollar actividades deportivas<\/span><\/i><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<div id=\"attachment_152750\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-152750\" class=\"size-full wp-image-152750\" src=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-1.jpg\" alt=\"A la inauguraci\u00f3n asistieron autoridades universitarias, estudiantes y entrenadores \" width=\"722\" height=\"487\" srcset=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-1.jpg 722w, https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-1-300x202.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><p id=\"caption-attachment-152750\" class=\"wp-caption-text\">A la inauguraci\u00f3n asistieron autoridades universitarias, estudiantes y entrenadores<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><b><i><span data-contrast=\"auto\">Carlos Hugo Hermida Rosales<\/span><\/i><\/b><\/p>\n<p><b><i><span data-contrast=\"auto\">13\/03\/2025, Xalapa, Ver.-<\/span><\/i><\/b><span data-contrast=\"auto\"> La Universidad Veracruzana (UV) rehabilit\u00f3 una cancha de futbol bardas e inaugur\u00f3 chanchas de tenis en la Unidad Deportiva del Campus para la\u202fCultura, las Artes y el Deporte\u202f(Campus CAD), en un acto encabezado por Mart\u00edn Aguilar S\u00e1nchez, rector de esta casa de estudios.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El Rector mencion\u00f3 que en la administraci\u00f3n universitaria se trabaja para que la comunidad estudiantil cuente con las condiciones adecuadas para desarrollar actividades deportivas, ya que inciden positivamente en la salud f\u00edsica y mental.<\/span><span data-ccp-props=\"{&quot;335559731&quot;:708}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">En su discurso, inst\u00f3 a los alumnos a vincular la pr\u00e1ctica del deporte de su preferencia con su formaci\u00f3n acad\u00e9mica, pues as\u00ed afrontar\u00e1n sus labores escolares de mejor manera.<\/span><\/p>\n<div id=\"attachment_152749\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-152749\" class=\"size-full wp-image-152749\" src=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-2.jpg\" alt=\"El Rector inst\u00f3 a los alumnos a vincular la pr\u00e1ctica del deporte de su preferencia con su formaci\u00f3n acad\u00e9mica \" width=\"722\" height=\"484\" srcset=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-2.jpg 722w, https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-2-300x201.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><p id=\"caption-attachment-152749\" class=\"wp-caption-text\">El Rector inst\u00f3 a los alumnos a vincular la pr\u00e1ctica del deporte de su preferencia con su formaci\u00f3n acad\u00e9mica<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">Mart\u00edn Aguilar destac\u00f3 que, en cuanto a representaciones deportivas, la Universidad ha avanzado en t\u00e9rminos de perspectiva de g\u00e9nero y un claro ejemplo de ello es el desarrollo y logros del equipo femenil de futbol r\u00e1pido.\u00a0<\/span><span data-ccp-props=\"{&quot;335559731&quot;:708}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cLa equidad entre sexos es fundamental en la convivencia, la cultura y la pr\u00e1ctica de deportes al interior de la Universidad\u201d, asegur\u00f3.<\/span><\/p>\n<div id=\"attachment_152748\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-152748\" class=\"size-full wp-image-152748\" src=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-3.jpg\" alt=\"La cancha de futbol bardas qued\u00f3 en condiciones \u00f3ptimas \" width=\"722\" height=\"516\" srcset=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-3.jpg 722w, https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-3-300x214.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><p id=\"caption-attachment-152748\" class=\"wp-caption-text\">La cancha de futbol bardas qued\u00f3 en condiciones \u00f3ptimas<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">El Rector felicit\u00f3 a los j\u00f3venes que practican alguna actividad deportiva, a sus docentes y entrenadores, y a la Fundaci\u00f3n UV \u2013responsable del mantenimiento del Campus CAD\u2013 por el esfuerzo realizado diariamente.<\/span><span data-ccp-props=\"{&quot;335559731&quot;:708}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Por su parte, Rosa Maribel Barradas Landa, titular de la Direcci\u00f3n General de Actividades Deportivas (DADUV), enfatiz\u00f3 en la importancia de celebrar el impacto del deporte en la formaci\u00f3n y bienestar de quienes integran la UV.<\/span><span data-ccp-props=\"{&quot;335559731&quot;:708}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cSu pr\u00e1ctica no solo contribuye a mejorar la condici\u00f3n f\u00edsica, pues tambi\u00e9n fortalece valores esenciales como disciplina, perseverancia, trabajo en equipo y resiliencia\u201d.\u00a0<\/span><\/p>\n<div id=\"attachment_152747\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-152747\" class=\"size-full wp-image-152747\" src=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-4.jpg\" alt=\"Las canchas de tenis servir\u00e1n para los alumnos que gustan de deporte blanco\" width=\"722\" height=\"498\" srcset=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-4.jpg 722w, https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-4-300x207.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><p id=\"caption-attachment-152747\" class=\"wp-caption-text\">Las canchas de tenis servir\u00e1n para los alumnos que gustan de deporte blanco<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">La directiva asegur\u00f3 que para la UV el deporte no es tan solo una actividad extracurricular, sino un componente transversal, fundamental en la formaci\u00f3n integral de los estudiantes.<\/span><span data-ccp-props=\"{&quot;335559731&quot;:708}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cLa rehabilitaci\u00f3n de las instalaciones deportivas es una inversi\u00f3n en el bienestar y rendimiento futuro de la comunidad universitaria\u201d, asever\u00f3.<\/span><span data-ccp-props=\"{&quot;335559731&quot;:708}\">\u00a0<\/span><\/p>\n<p><span class=\"TextRun SCXW59520873 BCX8\" lang=\"ES-MX\" xml:lang=\"ES-MX\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">Al evento asistieron Juan Ortiz Escamilla, Lizbeth Viveros <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">Cancino<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\"> y Jaqueline <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">Jongitud<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\"> Za<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">mora, titulares de las secretar\u00ed<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">as Acad\u00e9mica, de Administraci\u00f3n y Finanzas y de Desarrollo Institucional, respectivamente; <\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">Miguel \u00c1ngel Cano <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">Asseleih<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">, director<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\"> de Proyectos, Construcciones y Mantenimiento<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">, y Facundo Enrique Pacheco Rojas, director general de la Fundaci\u00f3n UV<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\">; as\u00ed como<\/span><span class=\"NormalTextRun SCXW59520873 BCX8\" data-ccp-parastyle=\"No Spacing\"> estudiantes, docentes, directivos y entrenadores.\u00a0<\/span><\/span><\/p>\n<div id=\"attachment_152751\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-152751\" class=\"size-full wp-image-152751\" src=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-5.jpg\" alt=\"Mart\u00edn Aguilar felicit\u00f3 a los j\u00f3venes que practican alguna actividad deportiva \" width=\"722\" height=\"508\" srcset=\"https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-5.jpg 722w, https:\/\/www.uv.mx\/prensa\/files\/2025\/03\/130325-CARLOS-Rehabilitacion-cancha-deportiva-5-300x211.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><p id=\"caption-attachment-152751\" class=\"wp-caption-text\">Mart\u00edn Aguilar felicit\u00f3 a los j\u00f3venes que practican alguna actividad deportiva<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Igualmente, se inauguraron canchas de tenis en el Campus CAD <\/p>\n","protected":false},"author":1775,"featured_media":152746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15423,1,61],"tags":[4161],"class_list":["post-152754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudiantes","category-general","category-banner","tag-carlos-hugo-hermida-rosales"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/posts\/152754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/users\/1775"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/comments?post=152754"}],"version-history":[{"count":1,"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/posts\/152754\/revisions"}],"predecessor-version":[{"id":152755,"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/posts\/152754\/revisions\/152755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/media\/152746"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/media?parent=152754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/categories?post=152754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/prensa\/wp-json\/wp\/v2\/tags?post=152754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}