{"id":16395,"date":"2016-08-15T08:59:11","date_gmt":"2016-08-15T13:59:11","guid":{"rendered":"https:\/\/www.uv.mx\/universo\/?p=16395"},"modified":"2016-08-15T11:27:41","modified_gmt":"2016-08-15T16:27:41","slug":"cursos-de-natacion-con-cupo-lleno","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/universo\/deportes\/cursos-de-natacion-con-cupo-lleno\/","title":{"rendered":"Cursos de Nataci\u00f3n, con cupo lleno"},"content":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529\" data-series-id=\"403\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 49 de 49 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/647\/\">647<\/a><\/div><\/div><\/div><div id=\"attachment_16327\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-066.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-16327\" class=\"size-full wp-image-16327\" src=\"https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-066.jpg\" alt=\"Diariamente asisten alrededor de 600 usuarios \" width=\"722\" height=\"481\" srcset=\"https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-066.jpg 722w, https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-066-300x200.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/a><p id=\"caption-attachment-16327\" class=\"wp-caption-text\">Diariamente asisten alrededor de 600 usuarios<\/p><\/div>\n<div id=\"attachment_16328\" style=\"width: 732px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-067.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-16328\" class=\"size-full wp-image-16328\" src=\"https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-067.jpg\" alt=\"Ger\u00f3nimo Guzm\u00e1n Salda\u00f1a, coordinador\" width=\"722\" height=\"481\" srcset=\"https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-067.jpg 722w, https:\/\/www.uv.mx\/universo\/files\/2016\/08\/Universo-647-067-300x200.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/a><p id=\"caption-attachment-16328\" class=\"wp-caption-text\">Ger\u00f3nimo Guzm\u00e1n Salda\u00f1a, coordinador<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><em>A la par, contin\u00faan las remodelaciones en la Alberca \u201cEulalio R\u00edos Torres\u201d<\/em><\/p>\n<p><span style=\"font-size: 10pt\"><strong>Santiago Morales Ortiz<\/strong><\/span><\/p>\n<p>Los cursos de Nataci\u00f3n de la Universidad Veracruzana se reanudaron con cupo lleno en la Alberca Universitaria \u201cEulalio R\u00edos Torres\u201d, a la par del proceso de remodelaci\u00f3n que contin\u00faa en algunas \u00e1reas de la misma, tras el periodo vacacional.<\/p>\n<p>Ger\u00f3nimo Guzm\u00e1n Salda\u00f1a, coordinador de la Escuela de Nataci\u00f3n de Halcones, se\u00f1al\u00f3 que la intenci\u00f3n de tales trabajos es que el escenario est\u00e9 en las mejores condiciones para la escuela, los cursos y el equipo de triatl\u00f3n: \u201cEstamos en el proceso de remodelaci\u00f3n, vamos en ese camino. Los usuarios tendr\u00e1n<br \/>\nun centro acu\u00e1tico integral\u201d.<\/p>\n<p>En la actualidad, se\u00f1al\u00f3, \u201cse est\u00e1 terminando con los vestidores y la colocaci\u00f3n de mamparas para la separaci\u00f3n de regaderas. Vamos poco a poco y pedimos la comprensi\u00f3n de los usuarios\u201d.<\/p>\n<p>El entrenador destac\u00f3 que los cursos se reanudaron hace ocho d\u00edas con cupo lleno en todos los horarios, desde las 6:00 hasta la 21:00 horas, en todas las categor\u00edas, incluyendo el curso de la campa\u00f1a de salud que ofrece la Universidad a sus trabajadores.<\/p>\n<p>Coment\u00f3 que son alrededor de 600 usuarios los que se atienden diariamente en la Alberca \u201cEulalio R\u00edos Torres\u201d. Adem\u00e1s, habl\u00f3 de los buenos resultados que ha tenido la Escuela de Halcones en los torneos estatales de curso largo y corto, con t\u00edtulos consecutivos durante nueve a\u00f1os.<\/p>\n<p>\u201cLos muchachos y padres de familia est\u00e1n entusiasmados, pues todos han contribuido al \u00e9xito obtenido durante estos a\u00f1os; ahora nos preparamos para el estatal de curso largo, que ser\u00e1 en diciembre.\u201d<\/p>\n<p>Con relaci\u00f3n a la Escuela de Clavados, Guzm\u00e1n Salda\u00f1a inform\u00f3 que se sigue el proceso de los arreglos en la fosa de la alberca, pues se trata de brindar un servicio de calidad.<br \/>\n\u201cEn el momento que la fosa est\u00e9 lista se reabrir\u00e1 la escuela, pues seguimos con la mira en los clavados ya que contamos tambi\u00e9n con el apoyo de la Asociaci\u00f3n Veracruzana de la especialidad para realizar cursos y actividades\u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529 pps-series-meta-excerpt\" data-series-id=\"403\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 49 de 49 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/647\/\">647<\/a><\/div><\/div><\/div><p>Los cursos de Nataci\u00f3n de la Universidad Veracruzana se reanudaron con cupo lleno en la Alberca Universitaria \u201cEulalio R\u00edos Torres\u201d, a la par del proceso de remodelaci\u00f3n que contin\u00faa en algunas \u00e1reas de la misma, tras el periodo vacacional.<\/p>\n","protected":false},"author":1869,"featured_media":16327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"series":[403],"class_list":["post-16395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","series-403"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/16395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/users\/1869"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/comments?post=16395"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/16395\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/media\/16327"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/media?parent=16395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/categories?post=16395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/tags?post=16395"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/series?post=16395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}