{"id":3892,"date":"2015-04-27T07:59:28","date_gmt":"2015-04-27T12:59:28","guid":{"rendered":"https:\/\/www.uv.mx\/universo\/?p=3892"},"modified":"2015-08-18T20:23:07","modified_gmt":"2015-08-19T01:23:07","slug":"la-palabra-y-el-hombre-nueva-imagen-mismo-espiritu","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/universo\/regiones\/la-palabra-y-el-hombre-nueva-imagen-mismo-espiritu\/","title":{"rendered":"La Palabra y el Hombre; nueva imagen, mismo esp\u00edritu"},"content":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529\" data-series-id=\"317\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 32 de 50 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/598\/\">598<\/a><\/div><\/div><\/div><p class=\"Encabezado\"><strong>Revista emblem\u00e1tica de la Universidad Veracruzana<\/strong><\/p>\n<div id=\"attachment_3860\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.uv.mx\/universo\/files\/2015\/04\/598-campus-007.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3860\" class=\"size-medium wp-image-3860\" src=\"https:\/\/www.uv.mx\/universo\/files\/2015\/04\/598-campus-007-300x198.jpg\" alt=\"Integrantes del Comit\u00e9 Editorial con el Vicerrector\" width=\"300\" height=\"198\" \/><\/a><p id=\"caption-attachment-3860\" class=\"wp-caption-text\">Integrantes del Comit\u00e9 Editorial con el Vicerrector<\/p><\/div>\n<p class=\"Titulo\"><span style=\"font-size: 10pt\"><strong>Alma Celia San Mart\u00edn<\/strong><\/span><\/p>\n<p class=\"Texto\"><strong>Poza Rica, Ver.-\u00a0<\/strong>La Unidad de Servicios Bibliotecarios y de Informaci\u00f3n (USBI) fue sede de la presentaci\u00f3n de la nueva imagen de La Palabra y el Hombre, revista emblem\u00e1tica de la Universidad Veracruzana que cumple 50 a\u00f1os y los celebra con un nuevo rostro pero con el mismo esp\u00edritu.<\/p>\n<p class=\"Texto\">En el evento participaron Mario Mu\u00f1oz, director de la revista; los acad\u00e9micos Leticia Mora y Xavier C\u00f3zar, moderados por Maril\u00fa Yamina Galv\u00e1n Dom\u00ednguez, todos integrantes del Consejo Editorial.<\/p>\n<p class=\"Texto\">Mu\u00f1oz ofreci\u00f3 una s\u00edntesis de la historia de la publicaci\u00f3n hasta llegar a la tercera \u00e9poca, en la que tiene un formato m\u00e1s ligero y acorde con una revista, lo cual permite la comuni\u00f3n de temas y confluencia de opiniones, sin que se sacrifique la seriedad y la calidad en los contenidos.<\/p>\n<p class=\"Texto\">A trav\u00e9s de los a\u00f1os se ha modificado el formato, el dise\u00f1o, la imagen y el diagramado; cada vez m\u00e1s participan en sus p\u00e1ginas colaboradores j\u00f3venes de las \u00e1reas acad\u00e9micas de Artes y Humanidades, entre otras, as\u00ed como escritores de reconocido prestigio.<\/p>\n<p class=\"Texto\">Leticia Mora, del Instituto de Investigaciones Ling\u00fc\u00edstico-Literarias, se refiri\u00f3 a la parte gr\u00e1fica de la revista e hizo comentarios interesantes e ilustrativos sobre diferentes temas que han sido publicados.<\/p>\n<p class=\"Texto\">Cit\u00f3, por ejemplo, el caso de un servidor p\u00fablico de Xalapa que se opuso a la proyecci\u00f3n de la pel\u00edcula Fresa y Chocolate con el argumento de preservar las tradiciones y valores; 20 a\u00f1os despu\u00e9s de esa pol\u00e9mica en el estado se ha impuesto una realidad m\u00e1s atroz y Fresa y Chocolate parece como un veraneo de ni\u00f1os.<\/p>\n<p class=\"Texto\">Otro tema abordado en la publicaci\u00f3n vers\u00f3 sobre \u201cLa Consagraci\u00f3n de la primavera, de Igor Stravinski, que en el Par\u00eds de 1913 con la interpretaci\u00f3n del Ballet Ruso, provoc\u00f3 que el p\u00fablico reaccionara con insultos y abucheos. En su momento esta presentaci\u00f3n romp\u00eda con los moldes cl\u00e1sicos a los que el p\u00fablico estaba acostumbrado\u201d.<\/p>\n<p class=\"Texto\">Estas an\u00e9cdotas son parte de la historia, es por ello que desde su fundaci\u00f3n la pol\u00edtica de La Palabra y el Hombre es dar cabida a todas las manifestaciones art\u00edsticas sin favoritismos ni perjuicios, atendiendo su calidad. En tanto, Xavier C\u00f3zar, director del Instituto de Artes Pl\u00e1sticas, coment\u00f3 sobre el papel que ha jugado el arte en la revista y dijo que \u00e9ste est\u00e1 \u201cencontrando su propio camino, un nuevo cauce creando cosas expresivas\u201d.<\/p>\n<p class=\"Texto\">Agreg\u00f3 que la UV apuesta porque el estudiante abra su panorama y est\u00e9 en condiciones de expresar lo que no le gusta: \u201cLos universitarios son personas cr\u00edticas, anal\u00edticas y pensantes, por lo tanto no se puede negar la posibilidad a una imagen\u201d.<\/p>\n<p class=\"Texto\">Por su parte Maril\u00fa Galv\u00e1n habl\u00f3 sobre la participaci\u00f3n de los integrantes del Consejo Editorial de la revista, a la hora de analizar los materiales que son propuestos para su publicaci\u00f3n.<\/p>\n<p class=\"Texto\">En el evento estuvo presente el vicerrector Jos\u00e9 Luis Alan\u00eds M\u00e9ndez, quien agradeci\u00f3 a los participantes su visita al campus: \u201cLa Palabra y el Hombre es una revista de gran prestigio que tiene una gran calidad tanto en los materiales como en los contenidos que presenta, que la sit\u00faan como una publicaci\u00f3n de gran tradici\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529 pps-series-meta-excerpt\" data-series-id=\"317\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 32 de 50 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/598\/\">598<\/a><\/div><\/div><\/div><p>Revista emblem\u00e1tica de la Universidad Veracruzana Alma Celia San Mart\u00edn Poza Rica, Ver.-\u00a0La Unidad de Servicios Bibliotecarios y de Informaci\u00f3n (USBI) fue sede de la presentaci\u00f3n de la nueva imagen de La Palabra y el Hombre, revista emblem\u00e1tica de la Universidad Veracruzana que cumple 50 a\u00f1os y los celebra con un nuevo rostro pero con [&hellip;]<\/p>\n","protected":false},"author":1668,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[360],"tags":[318],"series":[317],"class_list":["post-3892","post","type-post","status-publish","format-standard","hentry","category-regiones","tag-318","series-317"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/3892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/users\/1668"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/comments?post=3892"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/3892\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/media?parent=3892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/categories?post=3892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/tags?post=3892"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/series?post=3892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}