{"id":4438,"date":"2015-04-20T07:59:53","date_gmt":"2015-04-20T12:59:53","guid":{"rendered":"https:\/\/www.uv.mx\/universo\/?p=4438"},"modified":"2015-10-28T18:02:51","modified_gmt":"2015-10-29T00:02:51","slug":"posgrados-tienen-mayor-calidad-y-demanda","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/universo\/general\/posgrados-tienen-mayor-calidad-y-demanda\/","title":{"rendered":"Posgrados tienen mayor calidad y demanda"},"content":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529\" data-series-id=\"324\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 7 de 46 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/597\/\">597<\/a><\/div><\/div><\/div><div id=\"attachment_4244\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.uv.mx\/universo\/files\/2015\/05\/597_008.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4244\" class=\"size-medium wp-image-4244\" src=\"https:\/\/www.uv.mx\/universo\/files\/2015\/05\/597_008-300x200.jpg\" alt=\"Leticia Rodr\u00edguez Audirac recorri\u00f3 la Expo Posgrado 2015 \" width=\"300\" height=\"200\" srcset=\"https:\/\/www.uv.mx\/universo\/files\/2015\/05\/597_008-300x200.jpg 300w, https:\/\/www.uv.mx\/universo\/files\/2015\/05\/597_008.jpg 722w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-4244\" class=\"wp-caption-text\">Leticia Rodr\u00edguez Audirac recorri\u00f3 la Expo Posgrado 2015<\/p><\/div>\n<p><span style=\"font-size: 8pt\"><strong>Paola Cort\u00e9s P\u00e9rez<\/strong><\/span><\/p>\n<p>La Universidad Veracruzana trabaja para asegurar la consolidaci\u00f3n y la calidad de sus 147 programas de posgrado, al ser fundamentales para el desarrollo de la instituci\u00f3n educativa, declar\u00f3 Leticia Rodr\u00edguez Audirac, secretaria Acad\u00e9mica, al inaugurar la VI Expo Posgrado 2015, cuyas actividades se realizaron el 17 y 18 de abril en la Casa del Lago.<\/p>\n<p>\u201cLa Universidad insiste en el fortalecimiento de su oferta de posgrados para distinguir, por un lado, aquellos que tienen potencial para ingresar al Programa Nacional de Posgrados de Calidad y, por otro, aquellos que dan respuesta a las necesidades sociales del estado.\u201d<\/p>\n<p>En tanto, Jos\u00e9 Rigoberto Gabriel Arg\u00fcelles, titular de la Direcci\u00f3n General de la Unidad de Estudios de Posgrado (DGUEP), dijo que la Expo Posgrado es id\u00f3nea para difundir la investigaci\u00f3n realizada a trav\u00e9s de los programas educativos de especialidades m\u00e9dicas, maestr\u00edas y doctorados que ofrece esta casa de estudios.<\/p>\n<p>\u201cLos posgrados del \u00c1rea Acad\u00e9mica Econ\u00f3mico-Administrativa son los de mayor demanda, dado que sus programas de licenciatura son los que tienen m\u00e1s egresados\u201d, refiri\u00f3 Gabriel Arg\u00fcelles.<\/p>\n<p>Por \u00faltimo, Patricia P\u00e9rez Ch\u00e1vez, coordinadora de Difusi\u00f3n de la DGUEP, especific\u00f3 que se ofrece informaci\u00f3n a los asistentes sobre los planes de estudios y proyectos de investigaci\u00f3n de aproximadamente 120 posgrados.<\/p>\n<p>\u201cCada a\u00f1o aumenta el n\u00famero de participantes en la Expo Posgrado. En la primera edici\u00f3n registramos cerca de 700 asistentes, el a\u00f1o pasado fueron dos mil y esperamos que este a\u00f1o la cifra sea superior.\u201d<\/p>\n<p>A la ceremonia de inauguraci\u00f3n asistieron Jos\u00e9 Velasco Toro, director del Consejo Veracruzano de Investigaci\u00f3n Cient\u00edfica y Desarrollo Tecnol\u00f3gico (Coveicydet); directores generales de \u00e1reas acad\u00e9micas, directores de algunas facultades, estudiantes de posgrado y de licenciatura, as\u00ed como p\u00fablico en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529 pps-series-meta-excerpt\" data-series-id=\"324\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 7 de 46 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/597\/\">597<\/a><\/div><\/div><\/div><p>La Universidad Veracruzana trabaja para asegurar la consolidaci\u00f3n y la calidad de sus 147 programas de posgrado, al ser fundamentales para el desarrollo de la instituci\u00f3n educativa, declar\u00f3 Leticia Rodr\u00edguez Audirac, secretaria Acad\u00e9mica, al inaugurar la VI Expo Posgrado 2015, cuyas actividades se realizaron el 17 y 18 de abril en la Casa del Lago.<\/p>\n","protected":false},"author":1664,"featured_media":4244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"series":[324],"class_list":["post-4438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","series-324"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/4438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/users\/1664"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/comments?post=4438"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/4438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/media\/4244"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/media?parent=4438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/categories?post=4438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/tags?post=4438"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/series?post=4438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}