{"id":6414,"date":"2014-11-10T07:59:12","date_gmt":"2014-11-10T13:59:12","guid":{"rendered":"https:\/\/www.uv.mx\/universo\/?p=6414"},"modified":"2016-01-04T16:23:46","modified_gmt":"2016-01-04T22:23:46","slug":"seleccion-de-basquetbol-enfocada-en-la-abe","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/universo\/deportes\/seleccion-de-basquetbol-enfocada-en-la-abe\/","title":{"rendered":"Selecci\u00f3n de Basquetbol, enfocada en la ABE"},"content":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529\" data-series-id=\"340\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 48 de 49 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/581\/\">581<\/a><\/div><\/div><\/div><div id=\"attachment_6314\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.uv.mx\/universo\/files\/2015\/05\/Temis_Universo-581_0061.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6314\" class=\"size-medium wp-image-6314\" src=\"https:\/\/www.uv.mx\/universo\/files\/2015\/05\/Temis_Universo-581_0061-300x225.jpg\" alt=\"\u201cEl objetivo es lograr una buena posici\u00f3n, figurar entre los ocho mejores\u201d: Ram\u00f3n \u201cRay\u201d Rodr\u00edguez\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.uv.mx\/universo\/files\/2015\/05\/Temis_Universo-581_0061-300x225.jpg 300w, https:\/\/www.uv.mx\/universo\/files\/2015\/05\/Temis_Universo-581_0061.jpg 722w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-6314\" class=\"wp-caption-text\">\u201cEl objetivo es lograr una buena posici\u00f3n, figurar entre los ocho mejores\u201d: Ram\u00f3n \u201cRay\u201d Rodr\u00edguez<\/p><\/div>\n<p><em>El equipo busca buenos resultados en el torneo y trabaja para calificar a la Universiada Nacional Monterrey 2015<\/em><\/p>\n<p><span style=\"font-size: 8pt\"><strong>Santiago Morales Ortiz<\/strong><\/span><\/p>\n<p>El entrenador de la Selecci\u00f3n de Basquetbol varonil de Halcones, Ram\u00f3n \u201cRay\u201d Rodr\u00edguez Gallardo, asume el reto de buscar buenos resultados dentro del torneo de la Asociaci\u00f3n de Basquetbol Estudiantil (ABE) y posteriormente lograr la calificaci\u00f3n a la Universiada Nacional Monterrey 2015.<\/p>\n<p>Campe\u00f3n del Festival Deportivo Universitario con el campus Xalapa, donde particip\u00f3 con un equipo integrado por nuevos valores y algunos refuerzos de la selecci\u00f3n, el entrenador se\u00f1al\u00f3 que actualmente est\u00e1 enfocado a la temporada de la ABE, en la cual ha mejorado el desempe\u00f1o de los deportistas universitarios.<\/p>\n<p>\u201cEn la ABE tenemos una temporada muy larga, con equipos muy fuertes. Vamos bien, vamos madurando como equipo, pues se trata de una liga con 19 selecciones de alto nivel.\u201d<\/p>\n<p>Destac\u00f3 que la base del equipo de Halcones son elementos del campus Xalapa, reforzado por un elemento de Veracruz y otro de Orizaba, quienes brindan su mejor esfuerzo dentro de la ABE.<\/p>\n<p>\u201cEl objetivo es lograr una buena posici\u00f3n, figurar entre los ocho mejores. Estamos enfocados en este torneo, posteriormente vendr\u00e1 la eliminatoria del Consejo Nacional del Deporte de la Educaci\u00f3n (Condde), que ser\u00e1 otro torneo de cara a la Universiada Nacional.\u201d<\/p>\n<p>\u201cRay\u201d Rodr\u00edguez calific\u00f3 como excelente el reconocimiento que las autoridades universitarias hicieron a los mejores deportistas del campus Xalapa, \u201cpues ellos tambi\u00e9n se esfuerzan y es justo que se les reconozca no s\u00f3lo en el deporte sino en lo acad\u00e9mico\u201d.<\/p>\n<p>Sobre las posibilidades de lograr la calificaci\u00f3n a la Universiada Nacional Monterrey 2015, el entrenador se\u00f1al\u00f3: \u201cEstamos en la Regi\u00f3n VII del Condde. Puebla e Hidalgo son fuertes, sin descartar a Oaxaca y Tlaxcala, pero como representantes de Veracruz tenemos muchas posibilidades\u201d.<\/p>\n<p>Finalmente agradeci\u00f3 el apoyo de las autoridades de la Universidad, que siempre est\u00e1n pendientes del deporte universitario y en especial de la Selecci\u00f3n de Basquetbol.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pps-series-post-details pps-series-post-details-variant-classic pps-series-post-details-25529 pps-series-meta-excerpt\" data-series-id=\"340\"><div class=\"pps-series-meta-content\"><div class=\"pps-series-meta-text\">Esta entrada es parte 48 de 49 en la serie <a href=\"https:\/\/www.uv.mx\/universo\/numero\/581\/\">581<\/a><\/div><\/div><\/div><p>El equipo busca buenos resultados en el torneo y trabaja para calificar a la Universiada Nacional Monterrey 2015 Santiago Morales Ortiz El entrenador de la Selecci\u00f3n de Basquetbol varonil de Halcones, Ram\u00f3n \u201cRay\u201d Rodr\u00edguez Gallardo, asume el reto de buscar buenos resultados dentro del torneo de la Asociaci\u00f3n de Basquetbol Estudiantil (ABE) y posteriormente lograr [&hellip;]<\/p>\n","protected":false},"author":1664,"featured_media":6314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"series":[340],"class_list":["post-6414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","series-340"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/6414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/users\/1664"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/comments?post=6414"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/posts\/6414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/media\/6314"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/media?parent=6414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/categories?post=6414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/tags?post=6414"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.uv.mx\/universo\/wp-json\/wp\/v2\/series?post=6414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}